{"id":14222,"count":1,"description":"","link":"https:\/\/mequipment.ro\/en\/tag\/sennebogen-724-g\/","name":"Sennebogen 724 G","slug":"sennebogen-724-g","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arhive Sennebogen 724 G - M. Equipment | Latest News in Construction, Mining &amp; Forestry Industry<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mequipment.ro\/tag\/sennebogen-724-g\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arhive Sennebogen 724 G - M. Equipment | Latest News in Construction, Mining &amp; Forestry Industry\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mequipment.ro\/tag\/sennebogen-724-g\/\" \/>\n<meta property=\"og:site_name\" content=\"M. Equipment | Latest News in Construction, Mining &amp; Forestry Industry\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MEqOfficial\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/mequipment.ro\\\/en\\\/tag\\\/sennebogen-724-g\\\/\",\"url\":\"https:\\\/\\\/mequipment.ro\\\/en\\\/tag\\\/sennebogen-724-g\\\/\",\"name\":\"Arhive Sennebogen 724 G - M. Equipment | Latest News in Construction, Mining &amp; Forestry Industry\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mequipment.ro\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mequipment.ro\\\/en\\\/tag\\\/sennebogen-724-g\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"description\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mequipment.ro\\\/tag\\\/sennebogen-724-g\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/mequipment.ro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sennebogen 724 G\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mequipment.ro\\\/#website\",\"url\":\"https:\\\/\\\/mequipment.ro\\\/\",\"name\":\"M. EQUIPMENT\",\"description\":\"News &amp; Media \u2502 Construction, Mining, Forestry\",\"publisher\":{\"@id\":\"https:\\\/\\\/mequipment.ro\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mequipment.ro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mequipment.ro\\\/#organization\",\"name\":\"M. Equipment\",\"url\":\"https:\\\/\\\/mequipment.ro\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mequipment.ro\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mequipment.ro\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/MEQ_512x512-.png\",\"contentUrl\":\"https:\\\/\\\/mequipment.ro\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/MEQ_512x512-.png\",\"width\":512,\"height\":512,\"caption\":\"M. Equipment\"},\"image\":{\"@id\":\"https:\\\/\\\/mequipment.ro\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mequipment.ro\\\/\",\"https:\\\/\\\/x.com\\\/MEqOfficial\",\"https:\\\/\\\/www.instagram.com\\\/mequipmentofficial\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/m-equipment\\\/?trk=biz-companies-cym\",\"https:\\\/\\\/ro.pinterest.com\\\/mequipment0694\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCf2OrMoKQCoHfc2CETKHBCA\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arhive Sennebogen 724 G - M. Equipment | Latest News in Construction, Mining &amp; Forestry Industry","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mequipment.ro\/tag\/sennebogen-724-g\/","og_locale":"en_US","og_type":"article","og_title":"Arhive Sennebogen 724 G - M. Equipment | Latest News in Construction, Mining &amp; Forestry Industry","og_url":"https:\/\/mequipment.ro\/tag\/sennebogen-724-g\/","og_site_name":"M. Equipment | Latest News in Construction, Mining &amp; Forestry Industry","twitter_card":"summary_large_image","twitter_site":"@MEqOfficial","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mequipment.ro\/en\/tag\/sennebogen-724-g\/","url":"https:\/\/mequipment.ro\/en\/tag\/sennebogen-724-g\/","name":"Arhive Sennebogen 724 G - M. Equipment | Latest News in Construction, Mining &amp; Forestry Industry","isPartOf":{"@id":"https:\/\/mequipment.ro\/#website"},"breadcrumb":{"@id":"https:\/\/mequipment.ro\/en\/tag\/sennebogen-724-g\/#breadcrumb"},"inLanguage":"en-US","description":""},{"@type":"BreadcrumbList","@id":"https:\/\/mequipment.ro\/tag\/sennebogen-724-g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/mequipment.ro\/"},{"@type":"ListItem","position":2,"name":"Sennebogen 724 G"}]},{"@type":"WebSite","@id":"https:\/\/mequipment.ro\/#website","url":"https:\/\/mequipment.ro\/","name":"M. EQUIPMENT","description":"News &amp; Media \u2502 Construction, Mining, Forestry","publisher":{"@id":"https:\/\/mequipment.ro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mequipment.ro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mequipment.ro\/#organization","name":"M. Equipment","url":"https:\/\/mequipment.ro\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mequipment.ro\/#\/schema\/logo\/image\/","url":"https:\/\/mequipment.ro\/wp-content\/uploads\/2025\/10\/MEQ_512x512-.png","contentUrl":"https:\/\/mequipment.ro\/wp-content\/uploads\/2025\/10\/MEQ_512x512-.png","width":512,"height":512,"caption":"M. Equipment"},"image":{"@id":"https:\/\/mequipment.ro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mequipment.ro\/","https:\/\/x.com\/MEqOfficial","https:\/\/www.instagram.com\/mequipmentofficial\/","https:\/\/www.linkedin.com\/company\/m-equipment\/?trk=biz-companies-cym","https:\/\/ro.pinterest.com\/mequipment0694\/","https:\/\/www.youtube.com\/channel\/UCf2OrMoKQCoHfc2CETKHBCA\/videos"]}]}},"_links":{"self":[{"href":"https:\/\/mequipment.ro\/en\/wp-json\/wp\/v2\/tags\/14222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mequipment.ro\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/mequipment.ro\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/mequipment.ro\/en\/wp-json\/wp\/v2\/posts?tags=14222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}